{"id":315,"date":"2025-08-27T21:12:17","date_gmt":"2025-08-27T21:12:17","guid":{"rendered":"https:\/\/zenkaisen.fr\/?p=315"},"modified":"2025-12-13T10:49:38","modified_gmt":"2025-12-13T10:49:38","slug":"ceremonie","status":"publish","type":"post","link":"https:\/\/zenkaisen.fr\/cs\/ceremonie\/","title":{"rendered":"Ob\u0159ady"},"content":{"rendered":"<p>Ob\u0159ady a ritu\u00e1ly prov\u00e1zely lidstvo odjak\u017eiva. Byly vyj\u00e1d\u0159en\u00edm \u00facty k n\u011b\u010demu v\u011bt\u0161\u00edmu ne\u017e \u010dlov\u011bk, jeho\u017e existenci na\u0161i p\u0159edkov\u00e9 tu\u0161ili ji\u017e od d\u00e1vn\u00fdch dob. N\u011bkdy to bylo Slunce, s\u00edly p\u0159\u00edrody, jindy m\u00fdtick\u00e9 bo\u017estvo, kter\u00e9 je zastupovalo.<\/p>\n\n\n\n<p>I kdy\u017e v zenu nejsou ob\u0159ady podstatou praxe, kterou z\u016fst\u00e1v\u00e1 v\u017edy zazen, jsou p\u0159esto p\u0159\u00edtomny. To n\u011bkdy p\u0159ekvapuje za\u010d\u00e1te\u010dn\u00edky, kte\u0159\u00ed je spojuj\u00ed s v\u00edrou, n\u00e1bo\u017eenstv\u00edm nebo uct\u00edv\u00e1n\u00edm Boha \u010di bo\u017estva. Jeliko\u017e v zenu neexistuje v\u00edra v Buddhu jako v boha, p\u0159ed k\u00fdm a \u010d\u00edm se klan\u00edme, zp\u00edv\u00e1me, p\u00e1l\u00edme kadidlo a p\u0159in\u00e1\u0161\u00edme ob\u011bti? Buddha symbolizuje p\u0159edev\u0161\u00edm na\u0161i vlastn\u00ed povahu probuzen\u00ed, z\u00e1klad na\u0161eho byt\u00ed, povahu v\u0161ech bytost\u00ed.<\/p>\n\n\n\n<p>Ob\u0159ady se obvykle konaj\u00ed po spole\u010dn\u00e9m zazenu a p\u0159ed j\u00eddlem. Zp\u011bvy jsou doprov\u00e1zeny r\u016fzn\u00fdmi n\u00e1stroji, jako je mokugyo \u2013 druh d\u0159ev\u011bn\u00e9ho \u00abmetronomu\u00bb slou\u017e\u00edc\u00edho k ud\u00e1v\u00e1n\u00ed rytmu, buben, kter\u00fd dod\u00e1v\u00e1 energii, nebo gong, kter\u00fd zd\u016fraz\u0148uje d\u016fle\u017eit\u00e9 momenty ob\u0159adu.<\/p>\n\n\n\n<p>P\u0159i spole\u010dn\u00e9m zp\u011bvu a poklon\u00e1ch se navz\u00e1jem harmonizujeme a vyjad\u0159ujeme vd\u011b\u010dnost za dary, kter\u00e9 ka\u017ed\u00fd den dost\u00e1v\u00e1me, jako je j\u00eddlo \u2013 duchovn\u00ed, tj. u\u010den\u00ed, i j\u00eddlo hmotn\u00e9. D\u00edky \u00fasil\u00ed nes\u010detn\u00fdch bytost\u00ed m\u016f\u017eeme \u017e\u00edt a praktikovat, a proto jim b\u011bhem ob\u0159ad\u016f symbolicky nab\u00edz\u00edme v\u0161echny z\u00e1sluhy plynouc\u00ed z na\u0161\u00ed meditace. Takov\u00fd p\u0159\u00edstup v n\u00e1s rozv\u00edj\u00ed \u0161t\u011bdrost, pokoru, vd\u011b\u010dnost a laskavost a na\u0161e sobeck\u00e9 sklony postupn\u011b sl\u00e1bnou.<\/p>\n\n\n\n<p>A\u010dkoli v zenu nen\u00ed nic \u00abposv\u00e1tn\u00e9ho\u00bb, pro toho, kdo praktikuje zenovou cestu, je ka\u017ed\u00e9 m\u00edsto posv\u00e1tn\u00e9, je to m\u00edsto cesty, kterou je ka\u017ed\u00fd z n\u00e1s. Ceremoni\u00e1l se tedy neomezuje pouze na dharmovou s\u00ed\u0148. Ka\u017ed\u00e1 ka\u017edodenn\u00ed \u010dinnost, pro\u017e\u00edvan\u00e1 s pozornost\u00ed, s pln\u00fdm nasazen\u00edm t\u011bla i mysli do toho, co pr\u00e1v\u011b d\u011bl\u00e1me, je ceremoni\u00e1lem.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les c\u00e9r\u00e9monies et les rituels ont toujours accompagn\u00e9 l&rsquo;humanit\u00e9. Ils \u00e9taient l&rsquo;expression d&rsquo;un hommage \u00e0 quelque chose de plus grand que l&rsquo;homme, dont nos anc\u00eatres pressentaient l&rsquo;existence depuis longtemps. Parfois [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9r\u00e9monies - Le Zen de Kaisen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenkaisen.fr\/cs\/ceremonie\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9r\u00e9monies - Le Zen de Kaisen\" \/>\n<meta property=\"og:description\" content=\"Les c\u00e9r\u00e9monies et les rituels ont toujours accompagn\u00e9 l&rsquo;humanit\u00e9. Ils \u00e9taient l&rsquo;expression d&rsquo;un hommage \u00e0 quelque chose de plus grand que l&rsquo;homme, dont nos anc\u00eatres pressentaient l&rsquo;existence depuis longtemps. Parfois [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenkaisen.fr\/cs\/ceremonie\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Zen de Kaisen\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-27T21:12:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T10:49:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/person\\\/73abb9f42b258573cc0c021695c279df\"},\"headline\":\"C\u00e9r\u00e9monies\",\"datePublished\":\"2025-08-27T21:12:17+00:00\",\"dateModified\":\"2025-12-13T10:49:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/\"},\"wordCount\":407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Sando-kaisen.jpg\",\"articleSection\":[\"Zen\"],\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/\",\"name\":\"C\u00e9r\u00e9monies - Le Zen de Kaisen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Sando-kaisen.jpg\",\"datePublished\":\"2025-08-27T21:12:17+00:00\",\"dateModified\":\"2025-12-13T10:49:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Sando-kaisen.jpg\",\"contentUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Sando-kaisen.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ceremonies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/zenkaisen.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e9r\u00e9monies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"name\":\"Le Zen de Kaisen\",\"description\":\"Zen\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\",\"name\":\"Le Zen de Kaisen\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"width\":300,\"height\":300,\"caption\":\"Le Zen de Kaisen\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/person\\\/73abb9f42b258573cc0c021695c279df\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zenkaisen.fr\"],\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/cs\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ceremonie \u2013 Zen Kaisen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenkaisen.fr\/cs\/ceremonie\/","og_locale":"cs_CZ","og_type":"article","og_title":"C\u00e9r\u00e9monies - Le Zen de Kaisen","og_description":"Les c\u00e9r\u00e9monies et les rituels ont toujours accompagn\u00e9 l&rsquo;humanit\u00e9. Ils \u00e9taient l&rsquo;expression d&rsquo;un hommage \u00e0 quelque chose de plus grand que l&rsquo;homme, dont nos anc\u00eatres pressentaient l&rsquo;existence depuis longtemps. Parfois [&hellip;]","og_url":"https:\/\/zenkaisen.fr\/cs\/ceremonie\/","og_site_name":"Le Zen de Kaisen","article_published_time":"2025-08-27T21:12:17+00:00","article_modified_time":"2025-12-13T10:49:38+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"admin","Odhadovan\u00e1 doba \u010dten\u00ed":"3 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zenkaisen.fr\/ceremonies\/#article","isPartOf":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/"},"author":{"name":"admin","@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/person\/73abb9f42b258573cc0c021695c279df"},"headline":"C\u00e9r\u00e9monies","datePublished":"2025-08-27T21:12:17+00:00","dateModified":"2025-12-13T10:49:38+00:00","mainEntityOfPage":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/"},"wordCount":407,"commentCount":0,"publisher":{"@id":"https:\/\/zenkaisen.fr\/ru\/#organization"},"image":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/#primaryimage"},"thumbnailUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg","articleSection":["Zen"],"inLanguage":"cs","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zenkaisen.fr\/ceremonies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zenkaisen.fr\/ceremonies\/","url":"https:\/\/zenkaisen.fr\/ceremonies\/","name":"Ceremonie \u2013 Zen Kaisen","isPartOf":{"@id":"https:\/\/zenkaisen.fr\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/#primaryimage"},"image":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/#primaryimage"},"thumbnailUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg","datePublished":"2025-08-27T21:12:17+00:00","dateModified":"2025-12-13T10:49:38+00:00","breadcrumb":{"@id":"https:\/\/zenkaisen.fr\/ceremonies\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenkaisen.fr\/ceremonies\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zenkaisen.fr\/ceremonies\/#primaryimage","url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg","contentUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Sando-kaisen.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/zenkaisen.fr\/ceremonies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/zenkaisen.fr\/"},{"@type":"ListItem","position":2,"name":"C\u00e9r\u00e9monies"}]},{"@type":"WebSite","@id":"https:\/\/zenkaisen.fr\/ru\/#website","url":"https:\/\/zenkaisen.fr\/ru\/","name":"Zen Kaisen","description":"Zen","publisher":{"@id":"https:\/\/zenkaisen.fr\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenkaisen.fr\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zenkaisen.fr\/ru\/#organization","name":"Zen Kaisen","url":"https:\/\/zenkaisen.fr\/ru\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","contentUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","width":300,"height":300,"caption":"Le Zen de Kaisen"},"image":{"@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/person\/73abb9f42b258573cc0c021695c279df","name":"admin","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/secure.gravatar.com\/avatar\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac2d1bcfda9e2c460076f93eddb0acee4839effc36e7365975685de10b6f20fe?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zenkaisen.fr"],"url":"https:\/\/zenkaisen.fr\/cs\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":1,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"predecessor-version":[{"id":316,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/posts\/315\/revisions\/316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}