{"id":1887,"date":"2024-07-26T18:21:29","date_gmt":"2024-07-26T16:21:29","guid":{"rendered":"https:\/\/www.zenkaisen.fr\/?post_type=tribe_events&#038;p=1887"},"modified":"2025-12-19T11:01:01","modified_gmt":"2025-12-19T11:01:01","slug":"jarni-dovolena-fr-cz-sk-2","status":"publish","type":"tribe_events","link":"https:\/\/zenkaisen.fr\/cs\/withdrawalr\/jarni-dovolena-fr-cz-sk-2\/","title":{"rendered":"Jarn\u00ed duchovn\u00ed cvi\u010den\u00ed \u2013 Francie, \u010cesk\u00e1 republika, Slovensko"},"content":{"rendered":"<p>Jste zv\u00e1ni k \u00fa\u010dasti na rekolekc\u00edch, kter\u00e9 vede mistr Sando Kaisen v kl\u00e1\u0161te\u0159e Pic Lumineux v Dordogne.<\/p>\n<p>\u00dastup je p\u0159\u00edle\u017eitost\u00ed k n\u00e1cviku tich\u00e9ho sezen\u00ed.\u00a0<em>zazen<\/em> \u2013 n\u011bkolikr\u00e1t denn\u011b se \u00fa\u010dastnit manu\u00e1ln\u00ed pr\u00e1ce, spole\u010dn\u00fdch j\u00eddel a odpo\u010dinku na zahrad\u011b.<\/p>\n<p>Je to jedine\u010dn\u00e1 p\u0159\u00edle\u017eitost setkat se s mistrem a komunitou praktikuj\u00edc\u00edch z r\u016fzn\u00fdch zem\u00ed a prohloubit svou praxi.<br \/>\nJe to skv\u011bl\u00e1 p\u0159\u00edle\u017eitost zapomenout na sebe a sledovat p\u0159irozen\u00fd rytmus v\u011bc\u00ed v souladu s ostatn\u00edmi a okoln\u00edm sv\u011btem.<\/p>\n<p>B\u011bhem zazen\u016f vyu\u010duje mistr Sando Kaisen formou\u00a0<em>kusens<\/em>.<br \/>\nJe tak\u00e9 mo\u017en\u00e9 kl\u00e1st mu ot\u00e1zky p\u0159\u00edmo b\u011bhem\u00a0<em>mondos<\/em>.<br \/>\nNa str\u00e1nk\u00e1ch\u00a0<em>kusens<\/em>\u00a0a\u00a0<em>mondos<\/em> jsou uvedeny ve francouz\u0161tin\u011b a p\u0159elo\u017eeny do \u010de\u0161tiny.<\/p>\n<p>Po\u010det m\u00edst je omezen na 25, aby byla zachov\u00e1na osobn\u00ed a p\u0159\u00e1telsk\u00e1 atmosf\u00e9ra.<\/p>\n<p><strong>Za\u010d\u00e1tek :<\/strong> 16. kv\u011btna, p\u0159\u00edjezd p\u0159ed ve\u010de\u0159\u00ed (mezi 16:00 a 20:00)<br \/>\n<strong>Konec :<\/strong> 24. kv\u011btna, po ob\u011bd\u011b a \u00faklidu m\u00edsta (kolem 16:00)<\/p>\n<p>P\u0159\u00edsp\u011bvek na dev\u00edtidenn\u00ed pobyt \u010din\u00ed 480 eur na osobu.<br \/>\nV t\u00e9to cen\u011b je zahrnuto v\u0161e (v\u00fduka, ubytov\u00e1n\u00ed, strava atd.).<\/p>\n<p><strong>Co si vz\u00edt s sebou :<\/strong><\/p>\n<ul>\n<li>pro zazen voln\u00fd, pohodln\u00fd \u010dern\u00fd nebo tmav\u00fd od\u011bv.<\/li>\n<li>abyste se rychle dostali do d\u00f3d\u017e\u00f3 a zase z n\u011bj ode\u0161li.\u00a0<em>zori<\/em>\u00a0- nebo sand\u00e1ly bez podpatk\u016f<\/li>\n<li>vhodn\u00fd od\u011bv a obuv pro pr\u00e1ci venku<\/li>\n<li>3 m\u00edsy a p\u0159\u00edbory<\/li>\n<li>toaletn\u00ed pot\u0159eby<\/li>\n<\/ul>\n<p>Existuj\u00ed\u00a0<em>zafus<\/em>\u00a0(pol\u0161t\u00e1\u0159) a\u00a0<em>futony<\/em>\u00a0(roho\u017ee) pro zazen, kter\u00e9 jsou k dispozici na m\u00edst\u011b.<br \/>\nRegistrovat se m\u016f\u017eete e-mailem:\u00a0<a href=\"mailto:zen-kaisen@wanadoo.fr\">zen-kaisen@wanadoo.fr<\/a>\u00a0nebo telefonicky: 06 23 30 18 56<br \/>\nV p\u0159\u00edpad\u011b jak\u00fdchkoli dotaz\u016f n\u00e1s nev\u00e1hejte kontaktovat.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates invit\u00e9s \u00e0 participer \u00e0 une retraite dirig\u00e9e par Ma\u00eetre Sando Kaisen au Monast\u00e8re du Pic Lumineux en Dordogne. Une retraite est l\u2019occasion de pratiquer l\u2019assise silencieuse \u2013\u00a0zazen \u2013 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2034,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1887","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie - Le Zen de Kaisen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenkaisen.fr\/cs\/withdrawalr\/jarni-dovolena-fr-cz-sk-2\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie - Le Zen de Kaisen\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates invit\u00e9s \u00e0 participer \u00e0 une retraite dirig\u00e9e par Ma\u00eetre Sando Kaisen au Monast\u00e8re du Pic Lumineux en Dordogne. Une retraite est l\u2019occasion de pratiquer l\u2019assise silencieuse \u2013\u00a0zazen \u2013 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenkaisen.fr\/cs\/withdrawalr\/jarni-dovolena-fr-cz-sk-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Zen de Kaisen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T11:01:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/\",\"name\":\"Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie - Le Zen de Kaisen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-07-26T16:21:29+00:00\",\"dateModified\":\"2025-12-19T11:01:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/retraitr\\\/retraite-de-printemps-fr-cz-sk-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/zenkaisen.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wydarzenia\",\"item\":\"https:\\\/\\\/zenkaisen.fr\\\/retraites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"name\":\"Le Zen de Kaisen\",\"description\":\"Zen\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\",\"name\":\"Le Zen de Kaisen\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"width\":300,\"height\":300,\"caption\":\"Le Zen de Kaisen\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jarn\u00ed retreat \u2013 Francie, \u010cesk\u00e1 republika, Slovensko - Zen Kaisen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenkaisen.fr\/cs\/withdrawalr\/jarni-dovolena-fr-cz-sk-2\/","og_locale":"cs_CZ","og_type":"article","og_title":"Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie - Le Zen de Kaisen","og_description":"Vous \u00eates invit\u00e9s \u00e0 participer \u00e0 une retraite dirig\u00e9e par Ma\u00eetre Sando Kaisen au Monast\u00e8re du Pic Lumineux en Dordogne. Une retraite est l\u2019occasion de pratiquer l\u2019assise silencieuse \u2013\u00a0zazen \u2013 [&hellip;]","og_url":"https:\/\/zenkaisen.fr\/cs\/withdrawalr\/jarni-dovolena-fr-cz-sk-2\/","og_site_name":"Le Zen de Kaisen","article_modified_time":"2025-12-19T11:01:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Odhadovan\u00e1 doba \u010dten\u00ed":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/","url":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/","name":"Jarn\u00ed retreat \u2013 Francie, \u010cesk\u00e1 republika, Slovensko - Zen Kaisen","isPartOf":{"@id":"https:\/\/zenkaisen.fr\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/#primaryimage"},"image":{"@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-07-26T16:21:29+00:00","dateModified":"2025-12-19T11:01:01+00:00","breadcrumb":{"@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/zenkaisen.fr\/retraitr\/retraite-de-printemps-fr-cz-sk-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/zenkaisen.fr\/"},{"@type":"ListItem","position":2,"name":"Wydarzenia","item":"https:\/\/zenkaisen.fr\/retraites\/"},{"@type":"ListItem","position":3,"name":"Retraite de printemps \u2013 France, R\u00e9publique tch\u00e8que, Slovaquie"}]},{"@type":"WebSite","@id":"https:\/\/zenkaisen.fr\/ru\/#website","url":"https:\/\/zenkaisen.fr\/ru\/","name":"Zen Kaisen","description":"Zen","publisher":{"@id":"https:\/\/zenkaisen.fr\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenkaisen.fr\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/zenkaisen.fr\/ru\/#organization","name":"Zen Kaisen","url":"https:\/\/zenkaisen.fr\/ru\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","contentUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","width":300,"height":300,"caption":"Le Zen de Kaisen"},"image":{"@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tribe_events\/1887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tribe_events\/1887\/revisions"}],"predecessor-version":[{"id":2433,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tribe_events\/1887\/revisions\/2433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/media?parent=1887"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tags?post=1887"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/zenkaisen.fr\/cs\/wp-json\/wp\/v2\/tribe_events_cat?post=1887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}