{"id":2521,"date":"2025-12-27T18:50:35","date_gmt":"2025-12-27T18:50:35","guid":{"rendered":"https:\/\/zenkaisen.fr\/?post_type=livre&#038;p=2521"},"modified":"2025-12-27T18:50:36","modified_gmt":"2025-12-27T18:50:36","slug":"zen-interior-dialogue","status":"publish","type":"livre","link":"https:\/\/zenkaisen.fr\/en\/book\/zen-interior-dialogue\/","title":{"rendered":"Zen, inner dialogue"},"content":{"rendered":"<p>Format: CD, Duration: 45 minutes<br>Publication date: 4 July 2003<br>Publisher: Univox<\/p>\n\n\n\n<p>This teaching by Sando Kaisen describes the state of the ignorant man, a puppet animated by the strings of his own projections. And how this same man discovers the meaning of life by knowing how to return to the source of the uncreated. There he finds unlimited freedom and the happiness of the great encounter with what has always been there.<br>\u00abThere is no other God but man himself when he awakens from his dream to truly be the Awakened One.\u00bb<\/p>\n\n\n\n<p>Audio clips:<\/p>\n\n\n\n<audio src=\"https:\/\/devteam.stronazen.pl\/old-zenkaisen\/wp-content\/uploads\/2024\/05\/13-zen-dialogue-interieur.mp3\" preload=\"none\" controls=\"controls\"><\/audio>","protected":false},"excerpt":{"rendered":"<p>Format : CD, Dur\u00e9e : 45&prime;Date de publication : 4 juillet 2003\u00c9diteur : Univox Cet enseignement de Sando Kaisen d\u00e9crit l\u2019\u00e9tat de l\u2019homme ignorant, marionnette anim\u00e9e par les ficelles de [&hellip;]<\/p>\n","protected":false},"featured_media":2494,"template":"","meta":{"_acf_changed":false},"class_list":["post-2521","livre","type-livre","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zen, dialogue int\u00e9rieur - Le Zen de Kaisen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenkaisen.fr\/en\/book\/zen-interior-dialogue\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zen, dialogue int\u00e9rieur - Le Zen de Kaisen\" \/>\n<meta property=\"og:description\" content=\"Format : CD, Dur\u00e9e : 45&prime;Date de publication : 4 juillet 2003\u00c9diteur : Univox Cet enseignement de Sando Kaisen d\u00e9crit l\u2019\u00e9tat de l\u2019homme ignorant, marionnette anim\u00e9e par les ficelles de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenkaisen.fr\/en\/book\/zen-interior-dialogue\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Zen de Kaisen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-27T18:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Zen-dialogue-interieur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/\",\"name\":\"Zen, dialogue int\u00e9rieur - Le Zen de Kaisen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Zen-dialogue-interieur.jpg\",\"datePublished\":\"2025-12-27T18:50:35+00:00\",\"dateModified\":\"2025-12-27T18:50:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Zen-dialogue-interieur.jpg\",\"contentUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Zen-dialogue-interieur.jpg\",\"width\":200,\"height\":202},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/livre\\\/zen-dialogue-interieur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/zenkaisen.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zen, dialogue int\u00e9rieur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"name\":\"Le Zen de Kaisen\",\"description\":\"Zen\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#organization\",\"name\":\"Le Zen de Kaisen\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/zenkaisen.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo.png\",\"width\":300,\"height\":300,\"caption\":\"Le Zen de Kaisen\"},\"image\":{\"@id\":\"https:\\\/\\\/zenkaisen.fr\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zen, inner dialogue - The Zen of Kaisen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenkaisen.fr\/en\/book\/zen-interior-dialogue\/","og_locale":"en_GB","og_type":"article","og_title":"Zen, dialogue int\u00e9rieur - Le Zen de Kaisen","og_description":"Format : CD, Dur\u00e9e : 45&prime;Date de publication : 4 juillet 2003\u00c9diteur : Univox Cet enseignement de Sando Kaisen d\u00e9crit l\u2019\u00e9tat de l\u2019homme ignorant, marionnette anim\u00e9e par les ficelles de [&hellip;]","og_url":"https:\/\/zenkaisen.fr\/en\/book\/zen-interior-dialogue\/","og_site_name":"Le Zen de Kaisen","article_modified_time":"2025-12-27T18:50:36+00:00","og_image":[{"width":200,"height":202,"url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Zen-dialogue-interieur.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/","url":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/","name":"Zen, inner dialogue - The Zen of Kaisen","isPartOf":{"@id":"https:\/\/zenkaisen.fr\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/#primaryimage"},"image":{"@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/#primaryimage"},"thumbnailUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Zen-dialogue-interieur.jpg","datePublished":"2025-12-27T18:50:35+00:00","dateModified":"2025-12-27T18:50:36+00:00","breadcrumb":{"@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/#primaryimage","url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Zen-dialogue-interieur.jpg","contentUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/12\/Zen-dialogue-interieur.jpg","width":200,"height":202},{"@type":"BreadcrumbList","@id":"https:\/\/zenkaisen.fr\/livre\/zen-dialogue-interieur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/zenkaisen.fr\/"},{"@type":"ListItem","position":2,"name":"Zen, dialogue int\u00e9rieur"}]},{"@type":"WebSite","@id":"https:\/\/zenkaisen.fr\/ru\/#website","url":"https:\/\/zenkaisen.fr\/ru\/","name":"The Zen of Kaisen","description":"Zen","publisher":{"@id":"https:\/\/zenkaisen.fr\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenkaisen.fr\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/zenkaisen.fr\/ru\/#organization","name":"The Zen of Kaisen","url":"https:\/\/zenkaisen.fr\/ru\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","contentUrl":"https:\/\/zenkaisen.fr\/wp-content\/uploads\/2025\/07\/logo.png","width":300,"height":300,"caption":"Le Zen de Kaisen"},"image":{"@id":"https:\/\/zenkaisen.fr\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenkaisen.fr\/en\/wp-json\/wp\/v2\/livre\/2521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenkaisen.fr\/en\/wp-json\/wp\/v2\/livre"}],"about":[{"href":"https:\/\/zenkaisen.fr\/en\/wp-json\/wp\/v2\/types\/livre"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zenkaisen.fr\/en\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/zenkaisen.fr\/en\/wp-json\/wp\/v2\/media?parent=2521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}